{"id":1125,"date":"2021-05-07T11:36:10","date_gmt":"2021-05-07T11:36:10","guid":{"rendered":"https:\/\/coolexplorers.com\/?page_id=1125"},"modified":"2025-01-26T17:56:08","modified_gmt":"2025-01-26T17:56:08","slug":"arrabida-tour","status":"publish","type":"page","link":"https:\/\/coolexplorers.com\/pt\/arrabida-tour\/","title":{"rendered":"Arr\u00e1bida Tour"},"content":{"rendered":"<section class=\"section\" id=\"section_2132804629\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"slider-wrapper relative\" id=\"slider-710018078\" >\n    <div class=\"slider slider-type-fade slider-nav-dots-dashes slider-nav-simple slider-nav-normal slider-nav-light slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": true,            \"wrapAround\": true,            \"autoPlay\": 5000,            \"pauseAutoPlayOnHover\" : false,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover is-full-height has-slide-effect slide-fade-in\" id=\"banner-2009018578\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-527896429\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-3717387005\" class=\"text\">\n\t\t\n\n<h1 class=\"uppercase\">Arr\u00e1bida Tour<\/h1>\n<h4><span style=\"font-weight: 400;\">Este tour ir\u00e1 lev\u00e1-lo a paisagens costeiras de tirar o f\u00f4lego, locais com hist\u00f3ria e vinhos fant\u00e1sticos<\/span><\/h4>\n\t\t\n<style>\n#text-3717387005 {\n  font-size: 0.75rem;\n}\n@media (min-width:550px) {\n  #text-3717387005 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/coolexplorers.com\/pt\/tours\/arrabida-tour\/\" target=\"_self\" class=\"button white\"  >\n    <span>RESERVE AGORA<\/span>\n  <\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-527896429 {\n  width: 82%;\n}\n#text-box-527896429 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2009018578 {\n  padding-top: 100%;\n}\n#banner-2009018578 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1.jpg);\n}\n#banner-2009018578 .overlay {\n  background-color: rgba(0, 0, 0, 0.4);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-127259803\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1802546112\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1802546112 {\n  width: 60%;\n}\n#text-box-1802546112 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-127259803 {\n  padding-top: 100%;\n}\n#banner-127259803 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-10889110\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-277185629\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-277185629 {\n  width: 60%;\n}\n#text-box-277185629 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-10889110 {\n  padding-top: 100%;\n}\n#banner-10889110 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-3.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-602756121\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1963360775\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1963360775 {\n  width: 60%;\n}\n#text-box-1963360775 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-602756121 {\n  padding-top: 100%;\n}\n#banner-602756121 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-4.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-185691588\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-395576493\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-395576493 {\n  width: 60%;\n}\n#text-box-395576493 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-185691588 {\n  padding-top: 100%;\n}\n#banner-185691588 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-5.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-599892501\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1226971054\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1226971054 {\n  width: 60%;\n}\n#text-box-1226971054 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-599892501 {\n  padding-top: 100%;\n}\n#banner-599892501 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-6.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-558236837\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1904649096\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1904649096 {\n  width: 60%;\n}\n#text-box-1904649096 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-558236837 {\n  padding-top: 100%;\n}\n#banner-558236837 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-7.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover is-full-height\" id=\"banner-1986763798\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1482584019\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1482584019 {\n  width: 60%;\n}\n#text-box-1482584019 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1986763798 {\n  padding-top: 100%;\n}\n#banner-1986763798 .bg.bg-loaded {\n  background-image: url(https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-8.jpg);\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2132804629 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1001327259\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-dashed\"  id=\"row-723371740\">\n\n\n\t<div id=\"col-737888157\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 70px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/rating-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/rating-300x300.png 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/rating-100x100.png 100w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/rating-150x150.png 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/rating.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-1974143868\" class=\"text\">\n\t\t\n\n<h4>TOUR INESQUEC\u00cdVEL <\/h4>\n\t\t\n<style>\n#text-1974143868 {\n  font-size: 1.5rem;\n  line-height: 1.75;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1308987764\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 70px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/wine-tasting-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/wine-tasting-300x300.png 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/wine-tasting-100x100.png 100w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/wine-tasting-150x150.png 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/wine-tasting.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2323865851\" class=\"text\">\n\t\t\n\n<h4>DEGUSTA\u00c7\u00c3O DE VINHO <\/h4>\n\t\t\n<style>\n#text-2323865851 {\n  font-size: 1.5rem;\n  line-height: 1.75;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1781397329\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 70px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/04\/euro-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/04\/euro-300x300.png 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/04\/euro-100x100.png 100w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/04\/euro-150x150.png 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/04\/euro.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2577666254\" class=\"text\">\n\t\t\n\n<h4>PRE\u00c7O A PARTIR DE \u20ac100<\/h4>\n\n\t\t\n<style>\n#text-2577666254 {\n  font-size: 1.5rem;\n  line-height: 1.75;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-723371740 > .col > .col-inner {\n  padding: 15px 20px 15px 20px;\n}\n@media (min-width:550px) {\n  #row-723371740 > .col > .col-inner {\n    padding: 5px 20px 5px 20px;\n  }\n}\n<\/style>\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1001327259 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:0.5em;margin-bottom:0.5em;max-width:1000px;height:1px;\"><\/div><\/div>\n\n\t<section class=\"section\" id=\"section_1686830963\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-165799570\">\n\n\n\t<div id=\"col-1731397314\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t<h4 class=\"uppercase text-left\">Informa\u00e7\u00f5es do Tour<\/h4>\n\t\t\t<ul class=\"nav nav-pills nav-vertical nav-uppercase nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-about\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_about\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_about\"><span>Sobre<\/span><\/a><\/li>\n<li id=\"tab-highlights\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_highlights\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_highlights\"><span>Highlights<\/span><\/a><\/li>\n<li id=\"tab-additional-options\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_additional-options\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_additional-options\"><span>Op\u00e7\u00f5es adicionais<\/span><\/a><\/li>\n<li id=\"tab-itinerary\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_itinerary\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_itinerary\"><span>ITINER\u00c1RIO<\/span><\/a><\/li>\n<li id=\"tab-adventure-map\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_adventure-map\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_adventure-map\"><span>Mapa da Aventura<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_about\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-about\">\n\n<p><span style=\"font-weight: 400;\">O tour da Arr\u00e1bida \u00e9 uma visita guiada privada de um dia em que poder\u00e1 desfrutar de algumas das vistas mais deslumbrantes de Portugal do topo do Parque Natural da Arr\u00e1bida.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O dia come\u00e7a a cruzar o rio Tejo na maravilhosa Ponte<\/span><span style=\"font-weight: 400;\"> \u00ba<\/span><span style=\"font-weight: 400;\"> de Abril passando pela est\u00e1tua do Cristo Rei. Durante o dia teremos paragens obrigat\u00f3rias nos locais mais emblem\u00e1ticos e interessantes como a Lagoa de Albufeira, o Cabo Espichel, o Castelo de Sesimbra, a vila piscat\u00f3ria de Sesimbra, uma tradicional f\u00e1brica de Azulejos e a Costa Azul onde iremos conduzir numa magn\u00edfica estrada costeira no interior do ex\u00f3tica \u00e1rea protegida do Parque Natural da Arr\u00e1bida descobrindo a sua natureza \u00fanica e paisagens deslumbrantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para terminar o dia da melhor forma iremos \u00e0 encantadora vila de Azeit\u00e3o para visitar uma das adegas mais famosas de Portugal com quase 200 anos de hist\u00f3ria. Ir\u00e1 ter uma visita guiada para aprender a hist\u00f3ria e o processo de produ\u00e7\u00e3o deste vinho, seguido de uma experi\u00eancia de degusta\u00e7\u00e3o de vinhos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 altura de regressar a Lisboa depois de um dia memor\u00e1vel passado connosco \u00e0 descoberta deste para\u00edso \u00fanico a bordo do nosso Land Rover Defender por caminhos que nenhum outro turista consegue alcan\u00e7ar.<\/span><\/p>\n\n<\/div>\n<div id=\"tab_highlights\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-highlights\">\n\n<ul>\n<li><span style=\"font-weight: 400;\">Paisagens deslumbrantes costeiras sobre o Oceano Atl\u00e2ntico e a Pen\u00ednsula de Tr\u00f3ia<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Atravesse a Ponte 25<\/span><span style=\"font-weight: 400;\">\u00ba<\/span><span style=\"font-weight: 400;\"> de Abril passando pela est\u00e1tua do Cristo Rei<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite o impressionante Cabo Espichel e a Lagoa de Albufeira<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Explore o Castelo de Sesimbra com vista sobre a pitoresca vila de Sesimbra<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Almo\u00e7o de peixe fresco e marisco na vila de pescadores de Sesimbra (opcional)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Descubra o magn\u00edfico Parque Natural da Arr\u00e1bida<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeie em uma das estradas mais bonitas de Portugal<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite uma tradicional f\u00e1brica de azulejos portugueses feitos \u00e0 m\u00e3o<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Experi\u00eancia de degusta\u00e7\u00e3o de vinhos&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite uma das adegas mais famosas de Portugal com quase 200 anos de hist\u00f3ria<\/span><\/li>\n<\/ul>\n\n<\/div>\n<div id=\"tab_additional-options\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-additional-options\">\n\n<p>As op\u00e7\u00f5es adicionais dependem da disponibilidade do guia e do itiner\u00e1rio no dia. Est\u00e3o sempre sujeitas \u00e0 disponibilidade e podem ter custos adicionais.<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeio de barco<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Observa\u00e7\u00e3o de golfinhos&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite v\u00e1rias adegas vin\u00edcolas localizadas na regi\u00e3o com experi\u00eancias de degusta\u00e7\u00e3o de vinhos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite a est\u00e1tua do Cristo Rei<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite o Castelo de Palmela<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visite o Convento da Arr\u00e1bida<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passeios a Cavalo pela magia e esplendor do Parque Natural da Arr\u00e1bida<\/span><\/li>\n<\/ul>\n<p><a href=\"https:\/\/coolexplorers.com\/pt\/contact\/\">Contate-nos<\/a> para obter mais informa\u00e7\u00f5es, caso queira adicionar alguma dessas op\u00e7\u00f5es ao seu tour.<\/p>\n\n<\/div>\n<div id=\"tab_itinerary\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-itinerary\">\n\n<p><b>Inicio<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Este passeio ir\u00e1 lev\u00e1-lo por paisagens costeiras de tirar o f\u00f4lego, locais com hist\u00f3ria e comida e vinhos fant\u00e1sticos. Vamos busc\u00e1-lo ao seu alojamento no nosso lend\u00e1rio Land Rover Defender.&nbsp;<\/span><\/p>\n<p><b>Parte I<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O Tour da Arr\u00e1bida come\u00e7a com a travessia do Rio Tejo na maravilhosa Ponte<\/span><span style=\"font-weight: 400;\">\u00ba<\/span><span style=\"font-weight: 400;\"> 25 de Abril.<\/span><span style=\"font-weight: 400;\">\u00ba<\/span><span style=\"font-weight: 400;\"> A Ponte 25 Abril \u00e9 uma ponte suspensa frequentemente comparada \u00e0 Golden Gate Bridge em S\u00e3o Francisco devido \u00e0s suas semelhan\u00e7as. No final da ponte, passar\u00e1 pela gigantesca est\u00e1tua do Cristo Rei erguida para expressar a gratid\u00e3o pelos portugueses terem sido poupados dos terr\u00edveis efeitos da Segunda Guerra Mundial.&nbsp;<\/span><\/p>\n<p><b>Parte II<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Seguimos agora para a Lagoa de Albufeira. Esta lagoa \u00e9 separada do mar por enormes dunas. Este \u00e9 um local de uma beleza \u00fanica, que alia a pureza do oceano, \u00e0s \u00e1guas da lagoa e extensos pinhais. A lagoa oferece \u00f3timas condi\u00e7\u00f5es para a pr\u00e1tica da pesca desportiva, vela ou windsurf.<\/span><\/p>\n<p><b>Parte III<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Chegou a altura de ir ao Cabo Espichel. O Cabo Espichel situa-se no ponto mais ocidental da costa de Sesimbra e combina a monumentalidade do edif\u00edcio com a imaterialidade da devo\u00e7\u00e3o religiosa e da beleza selvagem \u00fanica. Este monumento est\u00e1 localizado em um planalto que termina em fal\u00e9sias majestosas sobre o mar tornando-o monumental.&nbsp;<\/span><\/p>\n<p><b>Parte IV<\/b><\/p>\n<p><span style=\"font-weight: 400;\">A pr\u00f3xima paragem ser\u00e1 no monumento nacional Castelo de Sesimbra. Este castelo medieval ocupa uma posi\u00e7\u00e3o dominante sobre uma fal\u00e9sia e os visitantes podem caminhar pelas muralhas e desfrutar de uma vista privilegiada sobre a pitoresca aldeia piscat\u00f3ria de Sesimbra e o mar. Depois de desfrutar desta maravilhosa vista, iremos descer a Sesimbra para a explorar. Sesimbra \u00e9 famosa pelas suas belas praias, peixe fresco e mar azul-turquesa.&nbsp;<\/span><\/p>\n<p><b>Parte V<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Hora de almo\u00e7o. Sugerimos que saboreie o peixe e marisco fresco que Sesimbra tem para oferecer. Vamos recomendar restaurantes que consideramos a melhor experi\u00eancia para os nossos clientes em termos de qualidade e pre\u00e7o. Por\u00e9m, se preferir pode trazer a sua pr\u00f3pria comida. Estacionaremos o Defender num local agrad\u00e1vel para que possa desfrutar da sua refei\u00e7\u00e3o com uma bonita paisagem.&nbsp;<\/span><\/p>\n<p><b>Parte VI<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s o almo\u00e7o, seguiremos para a Costa Azul onde faremos um passeio pela maravilhosa estrada costeira dentro da Serra da Arr\u00e1bida integrada na \u00e1rea protegida do Parque Natural da Arr\u00e1bida. Aqui encontrar\u00e1 uma fauna e flora mediterr\u00e2nea muito rica, vegeta\u00e7\u00e3o densa, praias incr\u00edveis e um oceano azul infinito. Uma dessas praias chama-se Galapinhos e j\u00e1 ganhou o pr\u00eamio de praia mais bonita da Europa. Durante esta parte do passeio, poder\u00e1 tirar fotos memor\u00e1veis no miradouro com vistas deslumbrantes sobre a Pen\u00ednsula de Tr\u00f3ia e o mar. A Arr\u00e1bida possui uma beleza natural incompar\u00e1vel que mistura as cores turquesa do oceano com a densa vegeta\u00e7\u00e3o verde e os tons brancos das arribas.&nbsp;<\/span><\/p>\n<p><b>Parte VII<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Visitaremos uma tradicional f\u00e1brica artesanal portuguesa de azulejos. Os azulejos fazem parte da nossa cultura e hist\u00f3ria e aprender\u00e1 como os azulejos s\u00e3o feitos de acordo com antigas tradi\u00e7\u00f5es e t\u00e9cnicas.&nbsp;<\/span><\/p>\n<p><b>Parte VIII<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No final do dia, faremos uma paragem em Vila Nogueira de Azeit\u00e3o para visitar uma das adegas mais famosas de Portugal com quase 200 anos de hist\u00f3ria. Ir\u00e1 fazer uma visita guiada \u00e0s caves da adega para aprender a hist\u00f3ria e o processo de produ\u00e7\u00e3o do vinho, seguido de uma experi\u00eancia de degusta\u00e7\u00e3o de vinhos. Azeit\u00e3o \u00e9 considerada uma das capitais da rota do vinho, com as suas adegas e vinhas que d\u00e3o vida a este precioso n\u00e9ctar denominado vinho. Tamb\u00e9m \u00e9 conhecida pelos seus deliciosos queijos e doces regionais.&nbsp;&nbsp;<\/span><\/p>\n<p><b>O fim<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 altura de regressar a Lisboa depois de um dia memor\u00e1vel passado connosco \u00e0 descoberta deste para\u00edso \u00fanico a bordo do nosso Land Rover Defender por caminhos que nenhum outro turista consegue alcan\u00e7ar.<\/span><\/p>\n\n<\/div>\n<div id=\"tab_adventure-map\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-adventure-map\">\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1993645957\">\n\t\t<a class=\"image-lightbox lightbox-gallery\" title=\"\" href=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map.jpg\">\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"2457\" height=\"1787\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map.jpg 2457w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-600x436.jpg 600w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-300x218.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-1024x745.jpg 1024w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-768x559.jpg 768w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-1536x1117.jpg 1536w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-map-2048x1490.jpg 2048w\" sizes=\"(max-width: 2457px) 100vw, 2457px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1993645957 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n<\/div><\/div><\/div>\n\t<div id=\"gap-2065669213\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2065669213 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1731397314 > .col-inner {\n  margin: 0px 0px -40px 0px;\n}\n@media (min-width:550px) {\n  #col-1731397314 > .col-inner {\n    margin: 0px 0px -20px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-882309873\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"uppercase\"><b>RESERVE ESTE TOUR<\/b><\/h3>\n<div class=\"woocommerce columns-1\"><div class=\"products row row-small large-columns-1 medium-columns-2 small-columns-2 has-equal-box-heights equalize-box\">\n<div class=\"product-small col has-hover product type-product post-1776 status-publish first instock product_cat-tours product_tag-arrabida has-post-thumbnail sold-individually shipping-taxable purchasable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/coolexplorers.com\/pt\/tours\/arrabida-tour\/\" aria-label=\"Arr\u00e1bida Tour\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2-300x300.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-banner-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/coolexplorers.com\/pt\/tours\/arrabida-tour\/\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable add_to_cart_button is-flat\" data-product_id=\"1776\" data-product_sku=\"AT\" aria-label=\"Seleccione as op\u00e7\u00f5es para \u201cArr\u00e1bida Tour\u201d\" aria-describedby=\"Este produto tem v\u00e1rias variantes. As op\u00e7\u00f5es podem ser escolhidas na p\u00e1gina do produto\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-aria-describedby=\"\">Ver op\u00e7\u00f5es<\/a><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div><!-- row -->\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-882309873 > .col-inner {\n  margin: 0px 0px -40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1450276693\">\n\n\n\t<div id=\"col-147978679\" class=\"col medium-9 small-12 large-9\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1610748556\" class=\"text\">\n\t\t\n\n<h3><b>Saiba antes de ir<\/b><\/h3>\n<p><i class=\"far fa-clock\"><\/i><span style=\"font-weight: 400;\">&nbsp;<strong>Dura\u00e7\u00e3o:<\/strong> 8 horas<\/span><\/p>\n<p><i class=\"fas fa-street-view\"><\/i><span style=\"font-weight: 400;\"><strong>&nbsp;Localiza\u00e7\u00e3o:<\/strong> Lisboa<\/span><\/p>\n<p><i class=\"far fa-compass\"><\/i>&nbsp;<strong>Pick up e drop off<\/strong> no seu alojamento em Lisboa.&nbsp;<\/p>\n<p><i class=\"far fa-question-circle\"><\/i><span style=\"font-weight: 400;\"><strong>&nbsp;N\u00e3o est\u00e1 em Lisboa?<\/strong> <a href=\"https:\/\/coolexplorers.com\/pt\/contact\/\">Contate-nos<\/a><\/span><\/p>\n\t\t\n<style>\n#text-1610748556 {\n  font-size: 1rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-147978679 > .col-inner {\n  margin: 0px 0px -40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-753542027\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-978905244\" class=\"text\">\n\t\t\n\n<h3><b>Pol\u00edtica de cancelamento<\/b><\/h3>\n<p>Para obter o reembolso total, cancele pelo menos 7 dias antes da data de in\u00edcio da experi\u00eancia.<\/p>\n\t\t\n<style>\n#text-978905244 {\n  font-size: 1rem;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/coolexplorers.com\/pt\/terms\/\" target=\"_self\" class=\"button alert is-small\"  style=\"border-radius:5px;\">\n    <span>Saber mais<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:0.5em;margin-bottom:0.5em;max-width:1050px;height:1px;\"><\/div><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1686830963 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n  margin-bottom: 0px;\n  min-height: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1873023340\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-540390282\">\n\n\n\t<div id=\"col-677193682\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe title=\"Endless Tours Portugal - Arr\u00e1bida Tour\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/YbMdRn7Bngg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t<h4 class=\"uppercase text-left\">Informa\u00e7\u00e3o importante<\/h4>\n\t\t\t<ul class=\"nav nav-pills nav-uppercase nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-what's-included\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_what's-included\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_what's-included\"><span>O que est\u00e1 inclu\u00eddo<\/span><\/a><\/li>\n<li id=\"tab-what's-not-included\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_what's-not-included\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_what's-not-included\"><span>O que n\u00e3o est\u00e1 inclu\u00eddo<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_what's-included\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-what's-included\">\n\n<div class=\"row\"  id=\"row-2138773461\">\n\n\n\t<div id=\"col-1240858822\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-user-tie\"><\/i><span style=\"font-weight: 400;\">&nbsp;Guia \/ motorista cool e exclusivo<\/span><\/p>\n<p><i class=\"fas fa-truck-monster\"><\/i><span style=\"font-weight: 400;\"> Um tour privado a bordo do lend\u00e1rio Land Rover Defender<\/span><\/p>\n<p><i class=\"fas fa-wifi\"><\/i> <span style=\"font-weight: 400;\">Wi-fi gr\u00e1tis&nbsp;<\/span><\/p>\n<p><i class=\"fas fa-music\"><\/i> <span style=\"font-weight: 400;\">Coluna Marshall com som incr\u00edvel<\/span><\/p>\n<p><i class=\"fab fa-bluetooth\"><\/i> <span style=\"font-weight: 400;\">Bluetooth<\/span><\/p>\n<p><i class=\"fas fa-battery-full\"><\/i> <span style=\"font-weight: 400;\">Tomadas de energia 220V (para smartphones \/ c\u00e2meras)<\/span><\/p>\n<p><i class=\"fas fa-shield-alt\"><\/i> <span style=\"font-weight: 400;\">Seguros Obrigat\u00f3rios<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1240858822 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-935434926\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-hamburger\"><\/i> <span style=\"font-weight: 400;\">\u00c1gua engarrafada e snacks a bordo<\/span><\/p>\n<p><i class=\"fas fa-umbrella-beach\"><\/i> <span style=\"font-weight: 400;\">Cobertores, toalhas de praia, guarda-chuvas<\/span><\/p>\n<p><i class=\"fas fa-gift\"><\/i> <span style=\"font-weight: 400;\">Surpresas durante o tour<\/span><\/p>\n<p><i class=\"fab fa-fort-awesome\"><\/i> <span style=\"font-weight: 400;\">Entrada no Castelo de Sesimbra<\/span><\/p>\n<p><i class=\"fas fa-wine-glass-alt\"><\/i><span style=\"font-weight: 400;\"> Experi\u00eancia de degusta\u00e7\u00e3o de vinhos<\/span><\/p>\n<p><i class=\"fas fa-heart\"><\/i> <span style=\"font-weight: 400;\">Muita divers\u00e3o e \u00f3timas mem\u00f3rias para levar para casa<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-935434926 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-899053302\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-899053302 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n<\/div>\n<div id=\"tab_what's-not-included\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-what's-not-included\">\n\n<p><i class=\"fas fa-utensils\"><\/i> <span style=\"font-weight: 400;\">Almo\u00e7o e bebidas<\/span><\/p>\n\n<\/div><\/div><\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-677193682 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1873023340 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-80236829\">\n\n\n\t<div id=\"col-1192948804\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"accordion\">\n\n\t<div id=\"accordion-620795715\" class=\"accordion-item\">\n\t\t<a id=\"accordion-620795715-label\" class=\"accordion-title plain\" href=\"#accordion-item-what_to_bring\" aria-expanded=\"false\" aria-controls=\"accordion-620795715-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>O que trazer<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-620795715-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-620795715-label\" >\n\t\t\t\n\n<div class=\"row\"  id=\"row-961836742\">\n\n\n\t<div id=\"col-229738615\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Protetor solar<\/span><\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Casaco \/ Sweater<\/span><\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Mochila \/ Bolsa<\/span><\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Roupas quentes \/ Casaco de chuva<\/span><\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Boas Vibra\u00e7\u00f5es<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-229738615 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n@media (min-width:550px) {\n  #col-229738615 > .col-inner {\n    margin: 0px 0px -30px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-539829299\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-check\"><\/i> Identifica\u00e7\u00e3o pessoal<\/p>\n<p><i class=\"fas fa-check\"><\/i> Roupas confort\u00e1veis&nbsp;<\/p>\n<p><i class=\"fas fa-check\"><\/i> Sapatos confort\u00e1veis<\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">Chap\u00e9u<\/span><\/p>\n<p><i class=\"fas fa-check\"><\/i> <span style=\"font-weight: 400;\">\u00d3culos de Sol&nbsp;<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-539829299 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1578579192\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1578579192-label\" class=\"accordion-title plain\" href=\"#accordion-item-good_to_know\" aria-expanded=\"false\" aria-controls=\"accordion-1578579192-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Bom saber<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1578579192-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1578579192-label\" >\n\t\t\t\n\n<div class=\"row\"  id=\"row-993477531\">\n\n\n\t<div id=\"col-1283139032\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-user-secret\"><\/i><span style=\"font-weight: 400;\"> Os nossos tours s\u00e3o sempre tours privados<\/span><\/p>\n<p><i class=\"fas fa-gem\"><\/i><span style=\"font-weight: 400;\"> Transporte em Land Rover Defender<\/span><\/p>\n<p><i class=\"fas fa-users\"><\/i> <span style=\"font-weight: 400;\">Capacidade: 1 motorista e 5 passageiros<\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3584110228\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3584110228-label\" class=\"accordion-title plain\" href=\"#accordion-item-available_languages\" aria-expanded=\"false\" aria-controls=\"accordion-3584110228-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Idiomas dispon\u00edveis<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3584110228-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3584110228-label\" >\n\t\t\t\n\n<div class=\"row\"  id=\"row-1932293956\">\n\n\n\t<div id=\"col-936698169\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p>Ingl\u00eas<\/p>\n<p>Portugu\u00eas<\/p>\n<p>Espanhol<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1205006741\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1205006741-label\" class=\"accordion-title plain\" href=\"#accordion-item-not_recommended\" aria-expanded=\"false\" aria-controls=\"accordion-1205006741-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>N\u00e3o recomendado<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1205006741-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1205006741-label\" >\n\t\t\t\n\n<div class=\"row\"  id=\"row-599653440\">\n\n\n\t<div id=\"col-589964680\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"fas fa-times-circle\"><\/i> <span style=\"font-weight: 400;\">Crian\u00e7as <\/span><b>com menos de 12 anos e \/ ou altura menor que 135 cm<\/b> <b>n\u00e3o s\u00e3o permitidas<\/b><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><i class=\"fas fa-times-circle\"><\/i><span style=\"font-weight: 400;\"> Devido \u00e0 acessibilidade do Land Rover Defender,<\/span><span style=\"font-weight: 400;\">pessoas com problemas de mobilidade, mulheres gr\u00e1vidas ou clientes com problemas nas costas <\/span><b>n\u00e3o s\u00e3o aconselhados.<\/b><\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-4159251789\" class=\"accordion-item\">\n\t\t<a id=\"accordion-4159251789-label\" class=\"accordion-title plain\" href=\"#accordion-item-need_help_booking?\" aria-expanded=\"false\" aria-controls=\"accordion-4159251789-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Alternar\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Precisa de ajuda para fazer a reserva?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-4159251789-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-4159251789-label\" >\n\t\t\t\n\n<div class=\"row\"  id=\"row-1265397259\">\n\n\n\t<div id=\"col-1880520035\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><i class=\"far fa-question-circle\"><\/i> <span style=\"font-weight: 400;\">Leia o nosso guia de <a href=\"https:\/\/coolexplorers.com\/pt\/faq\/\">perguntas frequentes<\/a><\/span><\/p>\n<p><i class=\"fas fa-phone\"><\/i><span style=\"font-weight: 400;\"><a href=\"https:\/\/coolexplorers.com\/pt\/contact\/\"> Contate-nos<\/a> ou Direct Whatsapp para mais informa\u00e7\u00f5es <a href=\"https:\/\/wa.me\/00351912453676\">+351 912 453 676<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1880520035 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<section class=\"section\" id=\"section_619731478\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-699702883\">\n\n\n\t<div id=\"col-740648417\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\" style=\"text-align: center;\"><span style=\"font-size: 130%;\">fotos deste tour<\/span><\/h2>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-740648417 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-864641995\">\n\n\n\t<div id=\"col-407051214\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1778038651\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:200%;\">\n\t\t\t<img width=\"1366\" height=\"2049\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1.jpg 1366w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-200x300.jpg 200w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-683x1024.jpg 683w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-768x1152.jpg 768w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-1024x1536.jpg 1024w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-8x12.jpg 8w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-100x150.jpg 100w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-1-600x900.jpg 600w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1778038651 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1662983055\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_303539138\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:200%;\">\n\t\t\t<img width=\"683\" height=\"1024\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-683x1024.jpg 683w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-200x300.jpg 200w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-768x1152.jpg 768w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-1024x1536.jpg 1024w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-8x12.jpg 8w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-100x150.jpg 100w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2-600x900.jpg 600w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-2.jpg 1366w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_303539138 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-330456919\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_963684728\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:200%;\">\n\t\t\t<img width=\"1366\" height=\"1823\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3.jpg\" class=\"attachment-original size-original\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3.jpg 1366w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-225x300.jpg 225w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-767x1024.jpg 767w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-768x1025.jpg 768w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-1151x1536.jpg 1151w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-9x12.jpg 9w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Arrabida-small-3-600x801.jpg 600w\" sizes=\"(max-width: 1366px) 100vw, 1366px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_963684728 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_619731478 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1556632276\">\n\n\n\t<div id=\"col-202499604\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"uppercase\" style=\"text-align: center;\"><span style=\"font-size: 130%;\">Tamb\u00e9m poder\u00e1 gostar\u2026<\/span><\/h2>\n<div class=\"row\"  id=\"row-313829086\">\n\n\n\t<div id=\"col-2089397278\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"woocommerce columns-3\"><div class=\"products row row-small large-columns-3 medium-columns-2 small-columns-2 has-equal-box-heights equalize-box\">\n<div class=\"product-small col has-hover product type-product post-1346 status-publish first instock product_cat-tours product_tag-cascais product_tag-sintra has-post-thumbnail sold-individually shipping-taxable purchasable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/coolexplorers.com\/pt\/tours\/sintra-cascais\/\" aria-label=\"Sintra - Cascais\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pena Palace\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-13x12.jpg 13w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-2-300x300.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-2-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-2-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-2-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Sintra-2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/coolexplorers.com\/pt\/tours\/sintra-cascais\/\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable add_to_cart_button is-flat\" data-product_id=\"1346\" data-product_sku=\"SC\" aria-label=\"Seleccione as op\u00e7\u00f5es para \u201cSintra - Cascais\u201d\" aria-describedby=\"Este produto tem v\u00e1rias variantes. As op\u00e7\u00f5es podem ser escolhidas na p\u00e1gina do produto\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-aria-describedby=\"\">Ver op\u00e7\u00f5es<\/a><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-1767 status-publish instock product_cat-tours product_tag-surf has-post-thumbnail sold-individually shipping-taxable purchasable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/coolexplorers.com\/pt\/tours\/surf-tour\/\" aria-label=\"Surf Tour\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner2-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner2-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner2-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner2-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner2-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner1-300x300.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner1-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner1-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner1-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Surf-banner1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/coolexplorers.com\/pt\/tours\/surf-tour\/\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable add_to_cart_button is-flat\" data-product_id=\"1767\" data-product_sku=\"ST\" aria-label=\"Seleccione as op\u00e7\u00f5es para \u201cSurf Tour\u201d\" aria-describedby=\"Este produto tem v\u00e1rias variantes. As op\u00e7\u00f5es podem ser escolhidas na p\u00e1gina do produto\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-aria-describedby=\"\">Ver op\u00e7\u00f5es<\/a><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><div class=\"product-small col has-hover product type-product post-1784 status-publish last instock product_cat-tours product_tag-comporta has-post-thumbnail sold-individually shipping-taxable purchasable product-type-variable\">\n\t<div class=\"col-inner\">\n\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t<div class=\"product-small box\">\n\t\t<div class=\"box-image\">\n\t\t\t<div class=\"image-fade_in_back\">\n\t\t\t\t<a href=\"https:\/\/coolexplorers.com\/pt\/tours\/comporta-tour\/\" aria-label=\"Comporta Tour\">\n\t\t\t\t\t<img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-6-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-6-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-6-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-6-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-6-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img width=\"300\" height=\"300\" src=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-1-300x300.jpg\" class=\"show-on-hover absolute fill hide-for-small back-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-1-300x300.jpg 300w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-1-150x150.jpg 150w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-1-85x85.jpg 85w, https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/05\/Comporta-banner-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small top right show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools is-small hide-for-small bottom left show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text box-text-products\">\n\t\t\t<div class=\"title-wrapper\"><\/div><div class=\"price-wrapper\"><\/div><div class=\"add-to-cart-button\"><a href=\"https:\/\/coolexplorers.com\/pt\/tours\/comporta-tour\/\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_variable add_to_cart_button is-flat\" data-product_id=\"1784\" data-product_sku=\"CT\" aria-label=\"Seleccione as op\u00e7\u00f5es para \u201cComporta Tour\u201d\" aria-describedby=\"Este produto tem v\u00e1rias variantes. As op\u00e7\u00f5es podem ser escolhidas na p\u00e1gina do produto\" rel=\"nofollow\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-aria-describedby=\"\">Ver op\u00e7\u00f5es<\/a><\/div>\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div><\/div><!-- row -->\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-50146908\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-50146908 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2114,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arr\u00e1bida Tour - Cool Explorers Portugal<\/title>\n<meta name=\"description\" content=\"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coolexplorers.com\/pt\/arrabida-tour\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arr\u00e1bida Tour - Cool Explorers Portugal\" \/>\n<meta property=\"og:description\" content=\"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coolexplorers.com\/pt\/arrabida-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Cool Explorers Portugal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-26T17:56:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/08\/cropped-cep-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/coolexplorers.com\/arrabida-tour\/\",\"url\":\"https:\/\/coolexplorers.com\/arrabida-tour\/\",\"name\":\"Arr\u00e1bida Tour - Cool Explorers Portugal\",\"isPartOf\":{\"@id\":\"https:\/\/coolexplorers.com\/pt\/#website\"},\"datePublished\":\"2021-05-07T11:36:10+00:00\",\"dateModified\":\"2025-01-26T17:56:08+00:00\",\"description\":\"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.\",\"breadcrumb\":{\"@id\":\"https:\/\/coolexplorers.com\/arrabida-tour\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/coolexplorers.com\/arrabida-tour\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/coolexplorers.com\/arrabida-tour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/coolexplorers.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arr\u00e1bida Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/coolexplorers.com\/pt\/#website\",\"url\":\"https:\/\/coolexplorers.com\/pt\/\",\"name\":\"Cool Explorers Portugal\",\"description\":\"Welcome to Portugal\u2019s #1 Tour Company\",\"publisher\":{\"@id\":\"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/539db40168aa4cadff4e057d280f1519\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/coolexplorers.com\/pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/539db40168aa4cadff4e057d280f1519\",\"name\":\"coolexplorers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/03\/cropped-Endless-Tours-Official-Logo-Smaller-Size-e1615812658859.png\",\"contentUrl\":\"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/03\/cropped-Endless-Tours-Official-Logo-Smaller-Size-e1615812658859.png\",\"width\":512,\"height\":512,\"caption\":\"coolexplorers\"},\"logo\":{\"@id\":\"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/coolexplorers.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arr\u00e1bida Tour - Cool Explorers Portugal","description":"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coolexplorers.com\/pt\/arrabida-tour\/","og_locale":"pt_PT","og_type":"article","og_title":"Arr\u00e1bida Tour - Cool Explorers Portugal","og_description":"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.","og_url":"https:\/\/coolexplorers.com\/pt\/arrabida-tour\/","og_site_name":"Cool Explorers Portugal","article_modified_time":"2025-01-26T17:56:08+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/08\/cropped-cep-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coolexplorers.com\/arrabida-tour\/","url":"https:\/\/coolexplorers.com\/arrabida-tour\/","name":"Arr\u00e1bida Tour - Cool Explorers Portugal","isPartOf":{"@id":"https:\/\/coolexplorers.com\/pt\/#website"},"datePublished":"2021-05-07T11:36:10+00:00","dateModified":"2025-01-26T17:56:08+00:00","description":"Enjoy some of the most stunning views in Portugal from the top of Arr\u00e1bida Natural Park and have an amazing Wine Tasting Experience.","breadcrumb":{"@id":"https:\/\/coolexplorers.com\/arrabida-tour\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coolexplorers.com\/arrabida-tour\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coolexplorers.com\/arrabida-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coolexplorers.com\/"},{"@type":"ListItem","position":2,"name":"Arr\u00e1bida Tour"}]},{"@type":"WebSite","@id":"https:\/\/coolexplorers.com\/pt\/#website","url":"https:\/\/coolexplorers.com\/pt\/","name":"Cool Explorers Portugal","description":"Welcome to Portugal\u2019s #1 Tour Company","publisher":{"@id":"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/539db40168aa4cadff4e057d280f1519"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coolexplorers.com\/pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":["Person","Organization"],"@id":"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/539db40168aa4cadff4e057d280f1519","name":"coolexplorers","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/03\/cropped-Endless-Tours-Official-Logo-Smaller-Size-e1615812658859.png","contentUrl":"https:\/\/coolexplorers.com\/wp-content\/uploads\/2021\/03\/cropped-Endless-Tours-Official-Logo-Smaller-Size-e1615812658859.png","width":512,"height":512,"caption":"coolexplorers"},"logo":{"@id":"https:\/\/coolexplorers.com\/pt\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/coolexplorers.com"]}]}},"_links":{"self":[{"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/pages\/1125"}],"collection":[{"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/comments?post=1125"}],"version-history":[{"count":4,"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/pages\/1125\/revisions"}],"predecessor-version":[{"id":2464,"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/pages\/1125\/revisions\/2464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/coolexplorers.com\/pt\/wp-json\/wp\/v2\/media?parent=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}